{"id":28183,"date":"2016-07-21T19:49:10","date_gmt":"2016-07-22T02:49:10","guid":{"rendered":"http:\/\/lifeboat.com\/blog\/2016\/07\/landscape-architect-bradley-cantrell-on-his-cyborg-ecologies"},"modified":"2017-06-04T14:31:47","modified_gmt":"2017-06-04T21:31:47","slug":"landscape-architect-bradley-cantrell-on-his-cyborg-ecologies","status":"publish","type":"post","link":"https:\/\/lifeboat.com\/blog\/2016\/07\/landscape-architect-bradley-cantrell-on-his-cyborg-ecologies","title":{"rendered":"Landscape architect Bradley Cantrell on his \u201ccyborg ecologies\u201d"},"content":{"rendered":"<p><a class=\"aligncenter blog-photo\" href=\"https:\/\/lifeboat.com\/blog.images\/landscape-architect-bradley-cantrell-on-his-cyborg-ecologies.jpg\"><\/a><\/p>\n<p>\u201cAs our technologies have gotten more advanced, [we have] more and more control over\u2026deeper levels of biological life.\u201d \u2014 Bradley Cantrell.<\/p>\n<p><!-- Link: <a href=\"http:\/\/archpaper.com\/2016\/07\/bradley-cantrell-landscape-architecture\/\">http:\/\/archpaper.com\/2016\/07\/bradley-cantrell-landscape-architecture\/<\/a> --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAs our technologies have gotten more advanced, [we have] more and more control over\u2026deeper levels of biological life.\u201d \u2014 Bradley Cantrell.<\/p>\n","protected":false},"author":395,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1499],"tags":[],"class_list":["post-28183","post","type-post","status-publish","format-standard","hentry","category-biological","category-cyborgs"],"_links":{"self":[{"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/posts\/28183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/users\/395"}],"replies":[{"embeddable":true,"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/comments?post=28183"}],"version-history":[{"count":3,"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/posts\/28183\/revisions"}],"predecessor-version":[{"id":66820,"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/posts\/28183\/revisions\/66820"}],"wp:attachment":[{"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/media?parent=28183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/categories?post=28183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifeboat.com\/blog\/wp-json\/wp\/v2\/tags?post=28183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}